{"id":177,"date":"2020-11-20T17:22:16","date_gmt":"2020-11-20T17:22:16","guid":{"rendered":"http:\/\/sites.ulethbridge.ca\/voicequest\/?page_id=177"},"modified":"2020-11-20T17:22:18","modified_gmt":"2020-11-20T17:22:18","slug":"europe","status":"publish","type":"page","link":"https:\/\/sites.ulethbridge.ca\/voicequest\/dialects\/dialect-samples\/europe\/","title":{"rendered":"Europe"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":19,"featured_media":0,"parent":99,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-177","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sites.ulethbridge.ca\/voicequest\/wp-json\/wp\/v2\/pages\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.ulethbridge.ca\/voicequest\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sites.ulethbridge.ca\/voicequest\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sites.ulethbridge.ca\/voicequest\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.ulethbridge.ca\/voicequest\/wp-json\/wp\/v2\/comments?post=177"}],"version-history":[{"count":1,"href":"https:\/\/sites.ulethbridge.ca\/voicequest\/wp-json\/wp\/v2\/pages\/177\/revisions"}],"predecessor-version":[{"id":178,"href":"https:\/\/sites.ulethbridge.ca\/voicequest\/wp-json\/wp\/v2\/pages\/177\/revisions\/178"}],"up":[{"embeddable":true,"href":"https:\/\/sites.ulethbridge.ca\/voicequest\/wp-json\/wp\/v2\/pages\/99"}],"wp:attachment":[{"href":"https:\/\/sites.ulethbridge.ca\/voicequest\/wp-json\/wp\/v2\/media?parent=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}